{"id":6889,"date":"2026-08-31T21:30:09","date_gmt":"2026-08-31T18:30:09","guid":{"rendered":"https:\/\/claypots.eu\/?post_type=product&#038;p=6889"},"modified":"2026-08-31T23:26:47","modified_gmt":"2026-08-31T20:26:47","slug":"mid-size-inside-white-glazed-clay-pot-casserole-dish","status":"publish","type":"product","link":"https:\/\/claypots.eu\/es\/product\/mid-size-inside-white-glazed-clay-pot-casserole-dish\/","title":{"rendered":"Cazuela mediana de barro esmaltada por dentro en blanco"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":6890,"template":"","meta":{"_yoast_wpseo_title":"","_yoast_wpseo_metadesc":"","_megzo_faq":"","_megzo_material":"","_megzo_capacity":"","_megzo_size":"","_megzo_manufacturing":"","_megzo_firing_temp":"","_megzo_oven_safe":"","_megzo_direct_flame":"","_megzo_dishwasher":"","_megzo_cleaning":"","_megzo_pallet_qty":"","_megzo_moq":"","_megzo_packaging":"","_megzo_brand":"","_megzo_is_cookware":"","_megzo_ean":"","_megzo_noindex":""},"product_brand":[],"product_cat":[521,518],"product_tag":[],"class_list":["post-6889","product","type-product","status-publish","has-post-thumbnail","product_cat-fuentes-barro-esmaltadas-por-dentro","product_cat-explora-nuestra-coleccion-completa-de-utensilios-de-terracota-artesanales-ollas-de-barro-naturales-fuentes-esmaltadas-y-accesorios-de-ceramica-para-mayoristas","first","instock","shipping-taxable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cazuela mediana de barro esmaltada por dentro en blanco - Terracotta Cookware Ceramic Cooking Clay Pots<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/claypots.eu\/es\/product\/mid-size-inside-white-glazed-clay-pot-casserole-dish\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cazuela mediana de barro esmaltada por dentro en blanco - Terracotta Cookware Ceramic Cooking Clay Pots\" \/>\n<meta property=\"og:url\" content=\"https:\/\/claypots.eu\/es\/product\/mid-size-inside-white-glazed-clay-pot-casserole-dish\/\" \/>\n<meta property=\"og:site_name\" content=\"Terracotta Cookware Ceramic Cooking Clay Pots\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/VasRoman\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-08-31T20:26:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/claypots.eu\/wp-content\/uploads\/2019\/05\/DSC_0381-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/claypots.eu\\\/es\\\/product\\\/mid-size-inside-white-glazed-clay-pot-casserole-dish\\\/\",\"url\":\"https:\\\/\\\/claypots.eu\\\/es\\\/product\\\/mid-size-inside-white-glazed-clay-pot-casserole-dish\\\/\",\"name\":\"Cazuela mediana de barro esmaltada por dentro en blanco - Terracotta Cookware Ceramic Cooking Clay Pots\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/claypots.eu\\\/es\\\/?lang=de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/claypots.eu\\\/es\\\/product\\\/mid-size-inside-white-glazed-clay-pot-casserole-dish\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/claypots.eu\\\/es\\\/product\\\/mid-size-inside-white-glazed-clay-pot-casserole-dish\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/claypots.eu\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/DSC_0381-2.jpg\",\"datePublished\":\"2026-08-31T18:30:09+00:00\",\"dateModified\":\"2026-08-31T20:26:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/claypots.eu\\\/es\\\/product\\\/mid-size-inside-white-glazed-clay-pot-casserole-dish\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/claypots.eu\\\/es\\\/product\\\/mid-size-inside-white-glazed-clay-pot-casserole-dish\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/claypots.eu\\\/es\\\/product\\\/mid-size-inside-white-glazed-clay-pot-casserole-dish\\\/#primaryimage\",\"url\":\"https:\\\/\\\/claypots.eu\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/DSC_0381-2.jpg\",\"contentUrl\":\"https:\\\/\\\/claypots.eu\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/DSC_0381-2.jpg\",\"width\":800,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/claypots.eu\\\/es\\\/product\\\/mid-size-inside-white-glazed-clay-pot-casserole-dish\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/claypots.eu\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"All products\",\"item\":\"https:\\\/\\\/claypots.eu\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Cazuela mediana de barro esmaltada por dentro en blanco\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/claypots.eu\\\/es\\\/?lang=de\\\/#website\",\"url\":\"https:\\\/\\\/claypots.eu\\\/es\\\/?lang=de\\\/\",\"name\":\"Terracotta Cookware Ceramic Cooking Clay Pots\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/claypots.eu\\\/es\\\/?lang=de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/claypots.eu\\\/es\\\/?lang=de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/claypots.eu\\\/es\\\/?lang=de\\\/#organization\",\"name\":\"Claypots EU - Terracotta Cookware\",\"url\":\"https:\\\/\\\/claypots.eu\\\/es\\\/?lang=de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/claypots.eu\\\/es\\\/?lang=de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/claypots.eu\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-final.png\",\"contentUrl\":\"https:\\\/\\\/claypots.eu\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-final.png\",\"width\":300,\"height\":259,\"caption\":\"Claypots EU - Terracotta Cookware\"},\"image\":{\"@id\":\"https:\\\/\\\/claypots.eu\\\/es\\\/?lang=de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/VasRoman\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@poem-design\"],\"legalName\":\"Poem Design Srl\",\"address\":{\"@type\":\"PostalAddress\",\"streetAddress\":\"Strada Berde M\u00f3zes 82\\\/F\",\"addressLocality\":\"Cristuru Secuiesc\",\"addressRegion\":\"Harghita\",\"postalCode\":\"535400\",\"addressCountry\":\"RO\"},\"telephone\":\"+40266243776\",\"email\":\"poemdesign@poem.ro\",\"vatID\":\"RO15196437\",\"taxID\":\"15196437\",\"alternateName\":\"Poem Design Ker\u00e1miabolt\",\"foundingDate\":\"2003\",\"identifier\":{\"@type\":\"PropertyValue\",\"propertyID\":\"CUI\",\"value\":\"15196437\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cazuela mediana de barro esmaltada por dentro en blanco - Terracotta Cookware Ceramic Cooking Clay Pots","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/claypots.eu\/es\/product\/mid-size-inside-white-glazed-clay-pot-casserole-dish\/","og_locale":"es_ES","og_type":"article","og_title":"Cazuela mediana de barro esmaltada por dentro en blanco - Terracotta Cookware Ceramic Cooking Clay Pots","og_url":"https:\/\/claypots.eu\/es\/product\/mid-size-inside-white-glazed-clay-pot-casserole-dish\/","og_site_name":"Terracotta Cookware Ceramic Cooking Clay Pots","article_publisher":"https:\/\/www.facebook.com\/VasRoman\/","article_modified_time":"2026-08-31T20:26:47+00:00","og_image":[{"width":800,"height":800,"url":"https:\/\/claypots.eu\/wp-content\/uploads\/2019\/05\/DSC_0381-2.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/claypots.eu\/es\/product\/mid-size-inside-white-glazed-clay-pot-casserole-dish\/","url":"https:\/\/claypots.eu\/es\/product\/mid-size-inside-white-glazed-clay-pot-casserole-dish\/","name":"Cazuela mediana de barro esmaltada por dentro en blanco - Terracotta Cookware Ceramic Cooking Clay Pots","isPartOf":{"@id":"https:\/\/claypots.eu\/es\/?lang=de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/claypots.eu\/es\/product\/mid-size-inside-white-glazed-clay-pot-casserole-dish\/#primaryimage"},"image":{"@id":"https:\/\/claypots.eu\/es\/product\/mid-size-inside-white-glazed-clay-pot-casserole-dish\/#primaryimage"},"thumbnailUrl":"https:\/\/claypots.eu\/wp-content\/uploads\/2019\/05\/DSC_0381-2.jpg","datePublished":"2026-08-31T18:30:09+00:00","dateModified":"2026-08-31T20:26:47+00:00","breadcrumb":{"@id":"https:\/\/claypots.eu\/es\/product\/mid-size-inside-white-glazed-clay-pot-casserole-dish\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/claypots.eu\/es\/product\/mid-size-inside-white-glazed-clay-pot-casserole-dish\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/claypots.eu\/es\/product\/mid-size-inside-white-glazed-clay-pot-casserole-dish\/#primaryimage","url":"https:\/\/claypots.eu\/wp-content\/uploads\/2019\/05\/DSC_0381-2.jpg","contentUrl":"https:\/\/claypots.eu\/wp-content\/uploads\/2019\/05\/DSC_0381-2.jpg","width":800,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/claypots.eu\/es\/product\/mid-size-inside-white-glazed-clay-pot-casserole-dish\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/claypots.eu\/es\/"},{"@type":"ListItem","position":2,"name":"All products","item":"https:\/\/claypots.eu\/shop\/"},{"@type":"ListItem","position":3,"name":"Cazuela mediana de barro esmaltada por dentro en blanco"}]},{"@type":"WebSite","@id":"https:\/\/claypots.eu\/es\/?lang=de\/#website","url":"https:\/\/claypots.eu\/es\/?lang=de\/","name":"Terracotta Cookware Ceramic Cooking Clay Pots","description":"","publisher":{"@id":"https:\/\/claypots.eu\/es\/?lang=de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/claypots.eu\/es\/?lang=de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/claypots.eu\/es\/?lang=de\/#organization","name":"Claypots EU - Terracotta Cookware","url":"https:\/\/claypots.eu\/es\/?lang=de\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/claypots.eu\/es\/?lang=de\/#\/schema\/logo\/image\/","url":"https:\/\/claypots.eu\/wp-content\/uploads\/2018\/07\/logo-final.png","contentUrl":"https:\/\/claypots.eu\/wp-content\/uploads\/2018\/07\/logo-final.png","width":300,"height":259,"caption":"Claypots EU - Terracotta Cookware"},"image":{"@id":"https:\/\/claypots.eu\/es\/?lang=de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/VasRoman\/","https:\/\/www.youtube.com\/@poem-design"],"legalName":"Poem Design Srl","address":{"@type":"PostalAddress","streetAddress":"Strada Berde M\u00f3zes 82\/F","addressLocality":"Cristuru Secuiesc","addressRegion":"Harghita","postalCode":"535400","addressCountry":"RO"},"telephone":"+40266243776","email":"poemdesign@poem.ro","vatID":"RO15196437","taxID":"15196437","alternateName":"Poem Design Ker\u00e1miabolt","foundingDate":"2003","identifier":{"@type":"PropertyValue","propertyID":"CUI","value":"15196437"}}]}},"_links":{"self":[{"href":"https:\/\/claypots.eu\/es\/wp-json\/wp\/v2\/product\/6889","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/claypots.eu\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/claypots.eu\/es\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":2,"href":"https:\/\/claypots.eu\/es\/wp-json\/wp\/v2\/product\/6889\/revisions"}],"predecessor-version":[{"id":7214,"href":"https:\/\/claypots.eu\/es\/wp-json\/wp\/v2\/product\/6889\/revisions\/7214"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/claypots.eu\/es\/wp-json\/wp\/v2\/media\/6890"}],"wp:attachment":[{"href":"https:\/\/claypots.eu\/es\/wp-json\/wp\/v2\/media?parent=6889"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/claypots.eu\/es\/wp-json\/wp\/v2\/product_brand?post=6889"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/claypots.eu\/es\/wp-json\/wp\/v2\/product_cat?post=6889"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/claypots.eu\/es\/wp-json\/wp\/v2\/product_tag?post=6889"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}